{"id":124,"count":1,"description":"","link":"https:\/\/enr.me.uk\/fromthenegative\/tag\/diy\/","name":"diy","slug":"diy","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/enr.me.uk\/fromthenegative\/wp-json\/wp\/v2\/tags\/124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enr.me.uk\/fromthenegative\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/enr.me.uk\/fromthenegative\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/enr.me.uk\/fromthenegative\/wp-json\/wp\/v2\/posts?tags=124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}